{"id":132,"count":2,"description":"","link":"https:\/\/www.nawaintertech.com\/th\/category\/%e0%b8%a3%e0%b8%b2%e0%b8%87%e0%b8%a7%e0%b8%b1%e0%b8%a5%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%a3%e0%b8%ad%e0%b8%87\/","name":"\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07","slug":"%e0%b8%a3%e0%b8%b2%e0%b8%87%e0%b8%a7%e0%b8%b1%e0%b8%a5%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%a3%e0%b8%ad%e0%b8%87","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07 Archives - \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e19\u0e27\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nawaintertech.com\/th\/category\/\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07 Archives - \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e19\u0e27\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nawaintertech.com\/th\/category\/\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e19\u0e27\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e17\u0e04 \u0e08\u0e33\u0e01\u0e31\u0e14\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@IntertechNawa\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.nawaintertech.com\/#organization\",\"name\":\"Nawa Intertech\",\"url\":\"https:\/\/www.nawaintertech.com\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/nawaintertech\",\"https:\/\/www.linkedin.com\/company\/nawaintertech\",\"https:\/\/www.youtube.com\/channel\/UCGm8R0qUUvmk6Yk85LCpm7g\",\"https:\/\/twitter.com\/IntertechNawa\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.nawaintertech.com\/#logo\",\"inLanguage\":\"th\",\"url\":\"\",\"caption\":\"Nawa Intertech\"},\"image\":{\"@id\":\"https:\/\/www.nawaintertech.com\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.nawaintertech.com\/#website\",\"url\":\"https:\/\/www.nawaintertech.com\/\",\"name\":\"\\u0e1a\\u0e23\\u0e34\\u0e29\\u0e31\\u0e17 \\u0e19\\u0e27\\u0e2d\\u0e34\\u0e19\\u0e40\\u0e15\\u0e2d\\u0e23\\u0e4c\\u0e40\\u0e17\\u0e04 \\u0e08\\u0e33\\u0e01\\u0e31\\u0e14\",\"description\":\"Nawaintertech\",\"publisher\":{\"@id\":\"https:\/\/www.nawaintertech.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.nawaintertech.com\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"th\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.nawaintertech.com\/th\/category\/%e0%b8%a3%e0%b8%b2%e0%b8%87%e0%b8%a7%e0%b8%b1%e0%b8%a5%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%a3%e0%b8%ad%e0%b8%87\/#webpage\",\"url\":\"https:\/\/www.nawaintertech.com\/th\/category\/%e0%b8%a3%e0%b8%b2%e0%b8%87%e0%b8%a7%e0%b8%b1%e0%b8%a5%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%a3%e0%b8%ad%e0%b8%87\/\",\"name\":\"\\u0e23\\u0e32\\u0e07\\u0e27\\u0e31\\u0e25\\u0e41\\u0e25\\u0e30\\u0e01\\u0e32\\u0e23\\u0e23\\u0e31\\u0e1a\\u0e23\\u0e2d\\u0e07 Archives - \\u0e1a\\u0e23\\u0e34\\u0e29\\u0e31\\u0e17 \\u0e19\\u0e27\\u0e2d\\u0e34\\u0e19\\u0e40\\u0e15\\u0e2d\\u0e23\\u0e4c\\u0e40\\u0e17\\u0e04 \\u0e08\\u0e33\\u0e01\\u0e31\\u0e14\",\"isPartOf\":{\"@id\":\"https:\/\/www.nawaintertech.com\/#website\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.nawaintertech.com\/th\/category\/%e0%b8%a3%e0%b8%b2%e0%b8%87%e0%b8%a7%e0%b8%b1%e0%b8%a5%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%a3%e0%b8%ad%e0%b8%87\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.nawaintertech.com\/th\/wp-json\/wp\/v2\/categories\/132\/"}],"collection":[{"href":"https:\/\/www.nawaintertech.com\/th\/wp-json\/wp\/v2\/categories\/"}],"about":[{"href":"https:\/\/www.nawaintertech.com\/th\/wp-json\/wp\/v2\/taxonomies\/category\/"}],"wp:post_type":[{"href":"https:\/\/www.nawaintertech.com\/th\/wp-json\/wp\/v2\/posts\/?categories=132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}